{"id":30512,"date":"2021-08-31T09:26:12","date_gmt":"2021-08-31T07:26:12","guid":{"rendered":"https:\/\/deftech.ch\/?p=30512"},"modified":"2021-08-31T09:51:34","modified_gmt":"2021-08-31T07:51:34","slug":"heute-spielen-morgen-gewinnen","status":"publish","type":"post","link":"https:\/\/deftech.ch\/it\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/","title":{"rendered":"Heute spielen, morgen gewinnen"},"content":{"rendered":"\n\t<section class=\"section\" id=\"section_473270384\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<p class=\"lead\">Mit <a href=\"https:\/\/deftech.ch\/wargaming\/\">Wargaming<\/a> und K\u00fcnstlicher Intelligenz ist es m\u00f6glich, Technologien zu testen, die so in der realen Welt noch gar nicht existieren. Die M\u00f6glichkeiten des <strong>Wargamings<\/strong> k\u00f6nnen auch Entscheidungstr\u00e4ger\/-innen der Schweizer Armee dabei helfen, neue <a href=\"https:\/\/www.ar.admin.ch\/de\/dokumente-und-publikationen\/armafolio-magazin.detail.publication.html\/ar-internet\/de\/publications\/publikationen\/armafolio-2021\/armafolio_2021-01_web.pdf.html\">Taktiken<\/a> und Einsatzverfahren zu entwickeln.<\/p>\n<p class=\"lead\">Um das Potenzial der K\u00fcnstlichen Intelligenz und Wargaming besser absch\u00e4tzen zu k\u00f6nnen, hat <a href=\"https:\/\/armasuisse.ch\/wt\">armasuisse W+T<\/a> erste Versuche mit einem <a href=\"https:\/\/deftech.ch\/wargaming\/\">Brett<\/a>&#8211; und Onlinespiel durchgef\u00fchrt.<\/p>\n<div class=\"row\"  id=\"row-1311833903\">\n<\/div>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_473270384 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n\n\t<section class=\"section\" id=\"section_1194441075\">\n\t\t<div class=\"section-bg fill\" >\n\t\t\t\t\t\t\t\t\t\n\t\t\t\n\n\t\t<\/div>\n\n\t\t\n\n\t\t<div class=\"section-content relative\">\n\t\t\t\n<p class=\"lead uppercase\" style=\"text-align: center;\"><a href=\"https:\/\/www.ar.admin.ch\/de\/dokumente-und-publikationen\/armafolio-magazin.detail.publication.html\/ar-internet\/de\/publications\/publikationen\/armafolio-2021\/armafolio_2021-01_web.pdf.html\">armafolio &#8211; 01 Juli 2021<\/a>\u00a0<\/p>\n\t\t<\/div>\n\n\t\t\n<style>\n#section_1194441075 {\n  padding-top: 30px;\n  padding-bottom: 30px;\n}\n<\/style>\n\t<\/section>\n\t\n<div class=\"row\"  id=\"row-1822312954\">\n\n\t<div id=\"col-16491517\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-851930424\" class=\"col medium-8 small-12 large-8\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t<div class=\"box has-hover   has-hover box-text-bottom\" >\n\n\t\t<div class=\"box-image\" >\n\t\t\t<a href=\"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/Heute-Spielen-Morgen-Gewinnen__armafolio-01-07-2021.pdf\" >\t\t\t<div class=\"\" >\n\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"595\" height=\"841\" src=\"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/armafolio_01-Juli-cover.jpg\" class=\"attachment- size-\" alt=\"\" srcset=\"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/armafolio_01-Juli-cover.jpg 595w, https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/armafolio_01-Juli-cover-212x300.jpg 212w\" sizes=\"auto, (max-width: 595px) 100vw, 595px\" \/>\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t<\/a>\t\t<\/div>\n\n\t\t<div class=\"box-text text-center\" >\n\t\t\t<div class=\"box-text-inner\">\n\t\t\t\t\n\t\t\t<\/div>\n\t\t<\/div>\n\t<\/div>\n\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n\n\t<div id=\"col-1642139389\" class=\"col medium-2 small-12 large-2\"  >\n\t\t\t\t<div class=\"col-inner\"  >\n\t\t\t\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\n\t\n<\/div>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":3,"featured_media":30513,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","default_image_id":0,"font":"","enabled":false},"version":2},"jetpack_post_was_ever_published":false},"categories":[40],"tags":[],"class_list":["post-30512","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-publications"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Heute spielen, morgen gewinnen - Deftech \u00b7 Defence Future Technologies<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"it_IT\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Heute spielen, morgen gewinnen - Deftech \u00b7 Defence Future Technologies\" \/>\n<meta property=\"og:url\" content=\"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/\" \/>\n<meta property=\"og:site_name\" content=\"Deftech \u00b7 Defence Future Technologies\" \/>\n<meta property=\"article:published_time\" content=\"2021-08-31T07:26:12+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-08-31T07:51:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/i2.wp.com\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg?fit=1460%2C904&ssl=1\" \/>\n\t<meta property=\"og:image:width\" content=\"1460\" \/>\n\t<meta property=\"og:image:height\" content=\"904\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Quentin Ladetto\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@deftechCH\" \/>\n<meta name=\"twitter:site\" content=\"@deftechCH\" \/>\n<meta name=\"twitter:label1\" content=\"Scritto da\" \/>\n\t<meta name=\"twitter:data1\" content=\"Quentin Ladetto\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tempo di lettura stimato\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/\"},\"author\":{\"name\":\"Quentin Ladetto\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/#\\\/schema\\\/person\\\/42813473d77c2ad33ae7ae983252b6ba\"},\"headline\":\"Heute spielen, morgen gewinnen\",\"datePublished\":\"2021-08-31T07:26:12+00:00\",\"dateModified\":\"2021-08-31T07:51:34+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/\"},\"wordCount\":121,\"publisher\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deftech.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/heute-spielen-morgen-gewinnen.jpg\",\"articleSection\":[\"Publications\"],\"inLanguage\":\"it-IT\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/\",\"url\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/\",\"name\":\"Heute spielen, morgen gewinnen - Deftech \u00b7 Defence Future Technologies\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/deftech.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/heute-spielen-morgen-gewinnen.jpg\",\"datePublished\":\"2021-08-31T07:26:12+00:00\",\"dateModified\":\"2021-08-31T07:51:34+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#breadcrumb\"},\"inLanguage\":\"it-IT\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#primaryimage\",\"url\":\"https:\\\/\\\/deftech.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/heute-spielen-morgen-gewinnen.jpg\",\"contentUrl\":\"https:\\\/\\\/deftech.ch\\\/wp-content\\\/uploads\\\/2021\\\/08\\\/heute-spielen-morgen-gewinnen.jpg\",\"width\":1460,\"height\":904},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/fr\\\/2021\\\/08\\\/31\\\/heute-spielen-morgen-gewinnen\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/deftech.ch\\\/it\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Heute spielen, morgen gewinnen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/#website\",\"url\":\"https:\\\/\\\/deftech.ch\\\/\",\"name\":\"Deftech - Defence Future Technologies\",\"description\":\"Inspire - Inform - Instruct\",\"publisher\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/deftech.ch\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"it-IT\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/#organization\",\"name\":\"Deftech - Defence Future Technologies\",\"alternateName\":\"Foresight Program by armasuisse Science and Technology\",\"url\":\"https:\\\/\\\/deftech.ch\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/i0.wp.com\\\/deftech.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/deftech-white-red-round-background.002.png?fit=1500%2C1500&ssl=1\",\"contentUrl\":\"https:\\\/\\\/i0.wp.com\\\/deftech.ch\\\/wp-content\\\/uploads\\\/2024\\\/09\\\/deftech-white-red-round-background.002.png?fit=1500%2C1500&ssl=1\",\"width\":1500,\"height\":1500,\"caption\":\"Deftech - Defence Future Technologies\"},\"image\":{\"@id\":\"https:\\\/\\\/deftech.ch\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/x.com\\\/deftechCH\",\"https:\\\/\\\/linkedin.com\\\/in\\\/ladetto\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/deftech.ch\\\/#\\\/schema\\\/person\\\/42813473d77c2ad33ae7ae983252b6ba\",\"name\":\"Quentin Ladetto\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"it-IT\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ea9f203bfc8c4bf31c42357b6fe4df547406af29b10b6e82d8b7ae2ae088af2?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ea9f203bfc8c4bf31c42357b6fe4df547406af29b10b6e82d8b7ae2ae088af2?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/7ea9f203bfc8c4bf31c42357b6fe4df547406af29b10b6e82d8b7ae2ae088af2?s=96&d=mm&r=g\",\"caption\":\"Quentin Ladetto\"},\"sameAs\":[\"https:\\\/\\\/ladetto.ch\\\/quentin-ladetto\",\"https:\\\/\\\/www.linkedin.com\\\/in\\\/ladetto\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Heute spielen, morgen gewinnen - Deftech \u00b7 Defence Future Technologies","robots":{"index":"noindex","follow":"follow"},"og_locale":"it_IT","og_type":"article","og_title":"Heute spielen, morgen gewinnen - Deftech \u00b7 Defence Future Technologies","og_url":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/","og_site_name":"Deftech \u00b7 Defence Future Technologies","article_published_time":"2021-08-31T07:26:12+00:00","article_modified_time":"2021-08-31T07:51:34+00:00","og_image":[{"width":1460,"height":904,"url":"https:\/\/i2.wp.com\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg?fit=1460%2C904&ssl=1","type":"image\/jpeg"}],"author":"Quentin Ladetto","twitter_card":"summary_large_image","twitter_creator":"@deftechCH","twitter_site":"@deftechCH","twitter_misc":{"Scritto da":"Quentin Ladetto","Tempo di lettura stimato":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#article","isPartOf":{"@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/"},"author":{"name":"Quentin Ladetto","@id":"https:\/\/deftech.ch\/#\/schema\/person\/42813473d77c2ad33ae7ae983252b6ba"},"headline":"Heute spielen, morgen gewinnen","datePublished":"2021-08-31T07:26:12+00:00","dateModified":"2021-08-31T07:51:34+00:00","mainEntityOfPage":{"@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/"},"wordCount":121,"publisher":{"@id":"https:\/\/deftech.ch\/#organization"},"image":{"@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg","articleSection":["Publications"],"inLanguage":"it-IT"},{"@type":"WebPage","@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/","url":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/","name":"Heute spielen, morgen gewinnen - Deftech \u00b7 Defence Future Technologies","isPartOf":{"@id":"https:\/\/deftech.ch\/#website"},"primaryImageOfPage":{"@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#primaryimage"},"image":{"@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#primaryimage"},"thumbnailUrl":"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg","datePublished":"2021-08-31T07:26:12+00:00","dateModified":"2021-08-31T07:51:34+00:00","breadcrumb":{"@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#breadcrumb"},"inLanguage":"it-IT","potentialAction":[{"@type":"ReadAction","target":["https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/"]}]},{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#primaryimage","url":"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg","contentUrl":"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg","width":1460,"height":904},{"@type":"BreadcrumbList","@id":"https:\/\/deftech.ch\/fr\/2021\/08\/31\/heute-spielen-morgen-gewinnen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/deftech.ch\/it\/"},{"@type":"ListItem","position":2,"name":"Heute spielen, morgen gewinnen"}]},{"@type":"WebSite","@id":"https:\/\/deftech.ch\/#website","url":"https:\/\/deftech.ch\/","name":"Deftech - Defence Future Technologies","description":"Inspire - Inform - Instruct","publisher":{"@id":"https:\/\/deftech.ch\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/deftech.ch\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"it-IT"},{"@type":"Organization","@id":"https:\/\/deftech.ch\/#organization","name":"Deftech - Defence Future Technologies","alternateName":"Foresight Program by armasuisse Science and Technology","url":"https:\/\/deftech.ch\/","logo":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/deftech.ch\/#\/schema\/logo\/image\/","url":"https:\/\/i0.wp.com\/deftech.ch\/wp-content\/uploads\/2024\/09\/deftech-white-red-round-background.002.png?fit=1500%2C1500&ssl=1","contentUrl":"https:\/\/i0.wp.com\/deftech.ch\/wp-content\/uploads\/2024\/09\/deftech-white-red-round-background.002.png?fit=1500%2C1500&ssl=1","width":1500,"height":1500,"caption":"Deftech - Defence Future Technologies"},"image":{"@id":"https:\/\/deftech.ch\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/x.com\/deftechCH","https:\/\/linkedin.com\/in\/ladetto"]},{"@type":"Person","@id":"https:\/\/deftech.ch\/#\/schema\/person\/42813473d77c2ad33ae7ae983252b6ba","name":"Quentin Ladetto","image":{"@type":"ImageObject","inLanguage":"it-IT","@id":"https:\/\/secure.gravatar.com\/avatar\/7ea9f203bfc8c4bf31c42357b6fe4df547406af29b10b6e82d8b7ae2ae088af2?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/7ea9f203bfc8c4bf31c42357b6fe4df547406af29b10b6e82d8b7ae2ae088af2?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/7ea9f203bfc8c4bf31c42357b6fe4df547406af29b10b6e82d8b7ae2ae088af2?s=96&d=mm&r=g","caption":"Quentin Ladetto"},"sameAs":["https:\/\/ladetto.ch\/quentin-ladetto","https:\/\/www.linkedin.com\/in\/ladetto\/"]}]}},"jetpack_publicize_connections":[],"jetpack_featured_media_url":"https:\/\/deftech.ch\/wp-content\/uploads\/2021\/08\/heute-spielen-morgen-gewinnen.jpg","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/paO9lW-7W8","_links":{"self":[{"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/posts\/30512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/comments?post=30512"}],"version-history":[{"count":0,"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/posts\/30512\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/media\/30513"}],"wp:attachment":[{"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/media?parent=30512"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/categories?post=30512"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deftech.ch\/it\/wp-json\/wp\/v2\/tags?post=30512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}